{"id":3279,"date":"2022-12-06T09:17:48","date_gmt":"2022-12-06T09:17:48","guid":{"rendered":"https:\/\/tmcadvisory.com\/alessandro-gasberti\/"},"modified":"2024-11-13T15:48:29","modified_gmt":"2024-11-13T15:48:29","slug":"alessandro-gasberti","status":"publish","type":"post","link":"https:\/\/tmcadvisory.com\/es\/alessandro-gasberti\/","title":{"rendered":"Alessandro Gasberti"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row bg_type=&#8221;video&#8221; video_url=&#8221;https:\/\/tmcadvisory.com\/wp-content\/uploads\/2022\/11\/sfondotmc1.mp4&#8243; video_opts=&#8221;loop,muted&#8221; video_poster=&#8221;id^93|url^https:\/\/tmcadvisory.com\/wp-content\/uploads\/2022\/11\/dettaglio-grigio1400x600.jpg|caption^null|alt^null|title^dettaglio grigio1400x600|description^null&#8221; viewport_vdo=&#8221;viewport_play&#8221; bg_override=&#8221;full&#8221;][vc_column][vc_empty_space height=&#8221;180&#8243;][vc_column_text]<span style=\"font-size: 24pt; color: #1e2b50;\">Alessandro Gasberti<\/span>[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#986f32&#8243;][vc_column_text]<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-size: 12pt; color: #1e2b50;\">Consultor Jur\u00eddico.<\/span><\/p>\n<p>[\/vc_column_text][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#986f32&#8243;][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<p style=\"font-weight: 400;\">Con una s\u00f3lida experiencia en derecho penal y laboral, me presento como una abogada emp\u00e1tica y fiable, centrada en establecer relaciones transparentes y directas con los clientes. Creo firmemente en la importancia de una comunicaci\u00f3n clara y aut\u00e9ntica para lograr resultados positivos. Por ello, me comprometo a prestar una asistencia jur\u00eddica eficaz y orientada a la resoluci\u00f3n de problemas, basada en una relaci\u00f3n de confianza mutua.  <\/p>\n<p style=\"font-weight: 400;\">En el \u00e1mbito del derecho laboral, he tenido la oportunidad de realizar numerosas consultas estrat\u00e9gicas para empresas sobre todas las cuestiones relacionadas con las relaciones laborales: planes de incentivos, reorganizaciones, reducciones de plantilla, amortiguadores sociales, traslados, contratos, pol\u00edticas de previsi\u00f3n y conflictos laborales, buscando siempre fomentar unas relaciones empresariales armoniosas y productivas.<\/p>\n<p style=\"font-weight: 400;\">Tambi\u00e9n he adquirido experiencia en el \u00e1mbito penal, especialmente en delitos fiscales, delitos concursales, derecho penal econ\u00f3mico, infracciones urban\u00edsticas, as\u00ed como delitos contra el patrimonio y la persona.<\/p>\n<p style=\"font-weight: 400;\">Est\u00e1n aqu\u00ed para ofrecerte un asesoramiento jur\u00eddico eficaz y proteger tus intereses con dedicaci\u00f3n y pericia.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1230&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_rounded&#8221; css_animation=&#8221;bounceInRight&#8221; css=&#8221;&#8221; lazy_loading=&#8221;true&#8221;]<div id=\"modal-trg-txt-wrap-3209\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin    \" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-3209 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#986f32;border-color:#986f32;color:#ffffff; \" data-class-id=\"content-6a049dd3e41c50-87393512\" class=\"btn-modal ult-responsive btn-primary btn-modal-sm overlay-show ult-align-left btn-id-6a049dd3e41c50-87393512\" data-overlay-class=\"overlay-zoomin\">FORMACI\u00d3N Y CERTIFICACIONES<\/button><\/div>\n<div class=\"ult-overlay content-6a049dd3e41c50-87393512 \" data-class=\"content-6a049dd3e41c50-87393512\" id=\"button-click-overlay\" style=\"background:rgba(30,43,80,0.8); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-medium\">\n\t<div class=\"ult-overlay-close popup-top-right\" style=\"width:40px;height:40px; background-color: #986f32;border-radius: 50%;padding:15px;box-sizing: content-box; \"><div class=\"ult-overlay-close-inside\">Close<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-7590\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#333333;\">\n\t\t\t<div class=\"ult_modal-header\" style=\"color:#333333;border-color:#333333;\">\n\t\t\t\t<div class=\"modal-icon\"><img decoding=\"async\" src=\"https:\/\/tmcadvisory.com\/wp-content\/uploads\/2022\/11\/LOGO_TMC_header.png\" class=\"ult-modal-inside-img\" alt=\"null\"><\/div><h3  data-ultimate-target='#ult-modal-wrap-7590 .ult_modal-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-title ult-responsive\">Formaci\u00f3n y certificaciones<\/h3>\n\t\t\t<\/div>\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-7590 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"background:#ffffff;\">\n\t\t\t<\/p>\n<p style=\"font-weight: 400;\">\nM\u00e1ster en Derecho &#8211; Universidad de Insubria Pr\u00e1cticas curriculares en el Tribunal de Busto Arsizio<\/p>\n<p style=\"font-weight: 400;\">\nAbogado Miembro del Colegio de Abogados de Varese<\/p>\n<p style=\"font-weight: 400;\">Miembro de la Sala de lo Penal de Varese.<\/p>\n<p><strong>Idiomas<\/strong><\/p>\n<p>Italiano<br \/>\nInglese<br \/>\nSpagnolo\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><div id=\"modal-trg-txt-wrap-3293\" class=\"ult-modal-input-wrapper ult-adjust-bottom-margin    \" data-keypress-control=\"keypress-control-enable\" data-overlay-control=\"overlay-control-enable\"><button  data-ultimate-target='#modal-trg-txt-wrap-3293 .btn-modal'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"background:#986f32;border-color:#986f32;color:#ffffff; \" data-class-id=\"content-6a049dd3e43953-02413903\" class=\"btn-modal ult-responsive btn-primary btn-modal-sm overlay-show ult-align-left btn-id-6a049dd3e43953-02413903\" data-overlay-class=\"overlay-zoomin\">EXPERIENCIA<\/button><\/div>\n<div class=\"ult-overlay content-6a049dd3e43953-02413903 \" data-class=\"content-6a049dd3e43953-02413903\" id=\"button-click-overlay\" style=\"background:rgba(30,43,80,0.8); display:none;\">\n\t<div class=\"ult_modal ult-fade ult-medium\">\n\t<div class=\"ult-overlay-close popup-top-right\" style=\"width:40px;height:40px; background-color: #986f32;border-radius: 50%;padding:15px;box-sizing: content-box; \"><div class=\"ult-overlay-close-inside\">Close<\/div><\/div>\n\t\t<div id=\"ult-modal-wrap-5633\" class=\"ult_modal-content ult-hide\" style=\"border-style:solid;border-width:2px;border-radius:0px;border-color:#333333;\">\n\t\t\t<div class=\"ult_modal-header\" style=\"color:#333333;border-color:#333333;\">\n\t\t\t\t<div class=\"modal-icon\"><img decoding=\"async\" src=\"https:\/\/tmcadvisory.com\/wp-content\/uploads\/2022\/11\/LOGO_TMC_header.png\" class=\"ult-modal-inside-img\" alt=\"null\"><\/div><h3  data-ultimate-target='#ult-modal-wrap-5633 .ult_modal-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-title ult-responsive\">Profesional experto en<\/h3>\n\t\t\t<\/div>\n\t\t\t<div  data-ultimate-target='#ult-modal-wrap-5633 .ult_modal-body'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult_modal-body ult-responsive ult-html\" style=\"background:#ffffff;\">\n\t\t\tDerecho laboral Derecho penal econ\u00f3mico Derecho fiscal<br \/>\n\n\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div>[\/vc_column_inner][\/vc_row_inner][vc_empty_space][vc_separator color=&#8221;custom&#8221; accent_color=&#8221;#986f32&#8243;][vc_column_text]<span style=\"color: #1e2b50; font-size: 14pt;\">Solicitar una consulta<\/span>[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3232-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"3232\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/3279#wpcf7-f3232-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3232\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3232-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:3232,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:&quot;200&quot;,&quot;animation_outtime&quot;:&quot;200&quot;,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:&quot;&quot;,&quot;notice_dismissed_rollback-cf7-6.1.3&quot;:true}}\" \/>\n<\/fieldset>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"N&lt;label&gt;ombre (Obligatorio)&lt;\/label&gt; Nombre\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><label>Apellidos (Obligatorio)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-745\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"Cognome\" aria-invalid=\"false\" value=\"Apellidos\" type=\"text\" name=\"text-745\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"C&lt;label&gt;orreo electr\u00f3nico (Obligatorio)&lt;\/label&gt; Correo electr\u00f3nico\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><label>Empresa<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-391\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"azienda\" aria-invalid=\"false\" value=\"Empresa\" type=\"text\" name=\"text-391\" \/><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><label>Naci\u00f3n<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nazione\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"nazione\"><option value=\"Italia Afganist\u00e1n Albania Argelia Andorra Angola Anguila Ant\u00e1rtida Antigua y Barbuda Antillas Neerlandesas Arabia Saud\u00ed Argentina Armenia Aruba Australia Austria Azerbaiy\u00e1n Bahamas Bahr\u00e9in Bangladesh Barbados B\u00e9lgica Belice Ben\u00edn Bermudas Bielorrusia But\u00e1n Bolivia Bosnia y Herzegovina Botsuana Brasil Brunei Darussalam Bulgaria Burkina Faso Burundi Cabo Verde Camboya Camer\u00fan Canad\u00e1 Chad Chile China Chipre Ciudad del Vaticano Colombia Comoras Corea del Norte Costa Rica C\u00f4te d&#039;Ivoire Croacia Cuba Dinamarca Dominica Ecuador Egipto Eire El Salvador Emiratos \u00c1rabes Unidos Eritrea Estonia Etiop\u00eda Federaci\u00f3n de Rusia Fiji Filipinas Finlandia Francia Gab\u00f3n Gambia Georgia Ghana Jamaica Jap\u00f3n Gibraltar Yibuti Jordania Grecia Granada Groenlandia Guadalupe Guatemala Guinea Guinea-issau Guinea Ecuatorial GuyanaBissau Guinea Ecuatorial Guayana Francesa Guyana Hait\u00ed Honduras Hong Kong India Indonesia Ir\u00e1n Iraq Isla Bouvet Isla de Navidad Islas Heard y McDonald Islas Caim\u00e1n Islas Cocos Islas Cook Islas Feroe\">Italia Afganist\u00e1n Albania Argelia Andorra Angola Anguila Ant\u00e1rtida Antigua y Barbuda Antillas Neerlandesas Arabia Saud\u00ed Argentina Armenia Aruba Australia Austria Azerbaiy\u00e1n Bahamas Bahr\u00e9in Bangladesh Barbados B\u00e9lgica Belice Ben\u00edn Bermudas Bielorrusia But\u00e1n Bolivia Bosnia y Herzegovina Botsuana Brasil Brunei Darussalam Bulgaria Burkina Faso Burundi Cabo Verde Camboya Camer\u00fan Canad\u00e1 Chad Chile China Chipre Ciudad del Vaticano Colombia Comoras Corea del Norte Costa Rica C\u00f4te d&#039;Ivoire Croacia Cuba Dinamarca Dominica Ecuador Egipto Eire El Salvador Emiratos \u00c1rabes Unidos Eritrea Estonia Etiop\u00eda Federaci\u00f3n de Rusia Fiji Filipinas Finlandia Francia Gab\u00f3n Gambia Georgia Ghana Jamaica Jap\u00f3n Gibraltar Yibuti Jordania Grecia Granada Groenlandia Guadalupe Guatemala Guinea Guinea-issau Guinea Ecuatorial GuyanaBissau Guinea Ecuatorial Guayana Francesa Guyana Hait\u00ed Honduras Hong Kong India Indonesia Ir\u00e1n Iraq Isla Bouvet Isla de Navidad Islas Heard y McDonald Islas Caim\u00e1n Islas Cocos Islas Cook Islas Feroe<\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"Islas Marshall Islas Marianas del Norte Islas menores alejadas de EE.UU. Islas Norfolk Islas Salom\u00f3n Islas Turcas y Caicos Islas V\u00edrgenes de EE.UU. Islas V\u00edrgenes Brit\u00e1nicas Israel Islandia Kazajst\u00e1n Kenia Kirguist\u00e1n Kiribati Kuwait Laos Letonia Lesoto L\u00edbano Liberia Liechtenstein Lituania Luxemburgo Macao Macedonia Madagascar Malasia Malawi Mal\u00ed Malta Marruecos Mauricio Mauritania Mayotte M\u00e9xico Moldavia M\u00f3naco Mongolia Montserrat Mozambique Liberia Libia Liechtenstein Lituania Luxemburgo Macao Macedonia Madagascar Malasia Malawi Mal\u00ed Malta Marruecos Mauricio Mauritania Mayotte M\u00e9xico Moldavia M\u00f3naco Mongolia Montserrat Mozambique Myanmar Namibia Nauru Nepal Nicaragua N\u00edger Nigeria Niue Noruega Nueva Nueva Caledonia Nueva Zelanda Om\u00e1n Pa\u00edses Bajos Pakist\u00e1n Palau Panam\u00e1 Pap\u00faa Nueva Guinea Paraguay Per\u00fa Pitcairn Polinesia Francesa Polonia Portugal Puerto Rico Qatar Reino Unido Rep\u00fablica Checa Rep\u00fablica Centroafricana Rep\u00fablica Democr\u00e1tica del Congo Rep\u00fablica Dominicana Rep\u00fablica Unida de Tanzan\u00eda Rumania Rwanda S\u00e1hara Occidental Saint Kitts y Nevis San Pedro y Miquel\u00f3n San Vicente y las Granadinas Samoa Americana San Marino Santa Elena Santa Luc\u00eda Santo Tom\u00e9 y Pr\u00edncipe Senegal Kosovo Seychelles Sierra Leona Singapur Siria Eslovaquia Eslovenia Somalia\">Islas Marshall Islas Marianas del Norte Islas menores alejadas de EE.UU. Islas Norfolk Islas Salom\u00f3n Islas Turcas y Caicos Islas V\u00edrgenes de EE.UU. Islas V\u00edrgenes Brit\u00e1nicas Israel Islandia Kazajst\u00e1n Kenia Kirguist\u00e1n Kiribati Kuwait Laos Letonia Lesoto L\u00edbano Liberia Liechtenstein Lituania Luxemburgo Macao Macedonia Madagascar Malasia Malawi Mal\u00ed Malta Marruecos Mauricio Mauritania Mayotte M\u00e9xico Moldavia M\u00f3naco Mongolia Montserrat Mozambique Liberia Libia Liechtenstein Lituania Luxemburgo Macao Macedonia Madagascar Malasia Malawi Mal\u00ed Malta Marruecos Mauricio Mauritania Mayotte M\u00e9xico Moldavia M\u00f3naco Mongolia Montserrat Mozambique Myanmar Namibia Nauru Nepal Nicaragua N\u00edger Nigeria Niue Noruega Nueva Nueva Caledonia Nueva Zelanda Om\u00e1n Pa\u00edses Bajos Pakist\u00e1n Palau Panam\u00e1 Pap\u00faa Nueva Guinea Paraguay Per\u00fa Pitcairn Polinesia Francesa Polonia Portugal Puerto Rico Qatar Reino Unido Rep\u00fablica Checa Rep\u00fablica Centroafricana Rep\u00fablica Democr\u00e1tica del Congo Rep\u00fablica Dominicana Rep\u00fablica Unida de Tanzan\u00eda Rumania Rwanda S\u00e1hara Occidental Saint Kitts y Nevis San Pedro y Miquel\u00f3n San Vicente y las Granadinas Samoa Americana San Marino Santa Elena Santa Luc\u00eda Santo Tom\u00e9 y Pr\u00edncipe Senegal Kosovo Seychelles Sierra Leona Singapur Siria Eslovaquia Eslovenia Somalia<\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"\"><\/option><option value=\"Espa\u00f1a\">Espa\u00f1a<\/option><option value=\"Sri Lanka Micronesia Estados Federados de Micronesia Estados Unidos de Am\u00e9rica Sud\u00e1frica Georgia del Sur y las Islas Sandwich Sud\u00e1n Surinam Svalbard y Jan Mayen Suecia Suiza Suazilandia Tailandia Tayikist\u00e1n Taiw\u00e1n Tanzania Territorio Brit\u00e1nico del Oc\u00e9ano \u00cdndico Territorios Franceses del Sur Territorios Palestinos Ocupados Timor Oriental Togo Tokelau Tonga Trinidad y Tobago T\u00fanez Turkmenist\u00e1n Turqu\u00eda Tuvalu Ucrania Uganda Hungr\u00eda Uruguay Uzbekist\u00e1n Vanuatu Venezuela Vietnam Wallis y Futuna Yemen Zambia Zimbabue Serbia Montenegro Timor Oriental Guernsey\">Sri Lanka Micronesia Estados Federados de Micronesia Estados Unidos de Am\u00e9rica Sud\u00e1frica Georgia del Sur y las Islas Sandwich Sud\u00e1n Surinam Svalbard y Jan Mayen Suecia Suiza Suazilandia Tailandia Tayikist\u00e1n Taiw\u00e1n Tanzania Territorio Brit\u00e1nico del Oc\u00e9ano \u00cdndico Territorios Franceses del Sur Territorios Palestinos Ocupados Timor Oriental Togo Tokelau Tonga Trinidad y Tobago T\u00fanez Turkmenist\u00e1n Turqu\u00eda Tuvalu Ucrania Uganda Hungr\u00eda Uruguay Uzbekist\u00e1n Vanuatu Venezuela Vietnam Wallis y Futuna Yemen Zambia Zimbabue Serbia Montenegro Timor Oriental Guernsey<\/option><\/select><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><label>\u00c1rea<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"area\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"area\"><option value=\"Fiscalidad Nacional Fiscalidad Internacional Finanzas Corporativas y Transacciones Extraordinarias Crisis y Reestructuraciones Corporativas ESG - Sostenibilidad Ecol\u00f3gica Fideicomisos y Activos Asistencia Jur\u00eddica Gobierno Corporativo Propiedad Intelectual\">Fiscalidad Nacional Fiscalidad Internacional Finanzas Corporativas y Transacciones Extraordinarias Crisis y Reestructuraciones Corporativas ESG - Sostenibilidad Ecol\u00f3gica Fideicomisos y Activos Asistencia Jur\u00eddica Gobierno Corporativo Propiedad Intelectual<\/option><\/select><\/span>\n\t<\/p>\n<\/div>\n<div class=\"full textarea\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-65\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" id=\"Incosapossiamoaiutarla\" aria-invalid=\"false\" name=\"textarea-65\">\u00bfEn qu\u00e9 podemos ayudarte?<\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"full\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-955\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-955\" value=\"1\" id=\"DichiarodiaverlettoeaccettatolInformativasullaprivacy\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Declaro que he le\u00eddo y acepto la Pol\u00edtica de privacidad. (Obligatorio)<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-512\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-512\" value=\"1\" id=\"Desideroriceverelanewsletter\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Deseo recibir el bolet\u00edn de noticias<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div class=\"full\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Env\u00eda\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"210\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[vc_empty_space][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p style=\"font-weight: 400;\"><strong>Abogado<\/strong><\/p>\n<p style=\"font-weight: 400;\">Soy experta en el \u00e1mbito del derecho laboral, habiendo tenido la oportunidad de realizar numerosas consultor\u00edas estrat\u00e9gicas para empresas sobre todas las cuestiones relacionadas con las relaciones laborales: planes de incentivos, reorganizaciones, reducciones de plantilla, amortiguadores sociales, traslados, contratos, pol\u00edticas de previsi\u00f3n y litigios laborales.<\/p>\n","protected":false},"author":1,"featured_media":2286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[127,122,133,141],"tags":[],"class_list":["post-3279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asociado","category-equipo","category-legal-es","category-varese-es","category-127","category-122","category-133","category-141","description-off"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/posts\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/comments?post=3279"}],"version-history":[{"count":1,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/posts\/3279\/revisions"}],"predecessor-version":[{"id":3284,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/posts\/3279\/revisions\/3284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/media\/2286"}],"wp:attachment":[{"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/categories?post=3279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tmcadvisory.com\/es\/wp-json\/wp\/v2\/tags?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}